{"id":4665,"date":"2021-11-30T05:11:54","date_gmt":"2021-11-30T05:11:54","guid":{"rendered":"https:\/\/demo.agnidesigns.com\/cartify\/?page_id=4665"},"modified":"2021-11-30T05:11:54","modified_gmt":"2021-11-30T05:11:54","slug":"about-us-2","status":"publish","type":"page","link":"https:\/\/faetm.com\/index.php\/about-us-2\/","title":{"rendered":"About Us 2"},"content":{"rendered":"\n<div class=\"agni-block-spacer agni-block-1648576618142\"><\/div>\n\n\n\n<div class=\"agni-block-paragraph has-text-align-center agni-block-1648576618148\"><p>Who We Are<\/p><\/div>\n\n\n\n<div class=\"agni-block-heading agni-block-1648576618153\"><h2 class=\"has-text-align-center\">New York Based eCommerce Platform Serving All Around the World<\/h2><\/div>\n\n\n\n<div class=\"agni-block-paragraph has-text-align-center agni-block-1648576618159\"><p>Nullam accumsan nulla in arcu condimentum imperdiet. Class aptent taciti sociosqu  litora torquent per conubia nostra, per inceptos himenaeos. Curabitur lacinia purus vitae lorem porttitor fermentum. In in mattis erat, eu mattis libero.<\/p><\/div>\n\n\n\n<div class=\"agni-block-buttons inline align-center agni-block-1648576618171\">\n<div class=\"agni-block-button agni-block-1648576618164\"><a class=\"btn\" href=\"https:\/\/demo.agnidesigns.com\/cartify\/our-team\/\" target=\"_self\" rel=\"noopener\"><span>Key People<\/span><\/a><\/div>\n<\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618174\"><\/div>\n\n\n\n<figure class=\"agni-block-image has-columns-wide size-full agni-block-1648576618178\"><img decoding=\"async\" src=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-6.png\" alt=\"\" class=\"wp-image-4744\"\/><\/figure>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618180\"><\/div>\n\n\n\n<div class=\"agni-block-separator has-display-style-5 has-align-center has-columns-full agni-block-1648576618183\"><div class=\"agni-block-separator-css\"><\/div><\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618194\"><\/div>\n\n\n\n<div class=\"agni-block-paragraph has-text-align-center agni-block-1648576618200\"><p>What we Do<\/p><\/div>\n\n\n\n<div class=\"agni-block-heading agni-block-1648576618206\"><h2 class=\"has-text-align-center\">Since 1985, we\u2019re creating the awesome products & promise to give high quality in the eCommerce market for all our customers residing any part of the world.<\/h2><\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618209\"><\/div>\n\n\n\n<div class=\"agni-block-gallery has-lightbox agni-block-1648576618219\"><ul class=\"agni-block-gallery-items\"><li class=\"agni-block-gallery-item\"><figure><a href=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-2.png\" target=\"_self\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-2.png\" alt=\"\" data-id=\"4740\" data-full-url=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-2.png\" data-link=\"https:\/\/demo.agnidesigns.com\/cartify\/about-image-2\/\" class=\"wp-image-4740\"\/><\/a><\/figure><\/li><li class=\"agni-block-gallery-item\"><figure><a href=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-7.png\" target=\"_self\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-7.png\" alt=\"\" data-id=\"4745\" data-full-url=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-7.png\" data-link=\"https:\/\/demo.agnidesigns.com\/cartify\/about-image-7\/\" class=\"wp-image-4745\"\/><\/a><\/figure><\/li><\/ul><\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618224\"><\/div>\n\n\n\n<div class=\"agni-block-separator has-display-style-5 has-align-center has-columns-full agni-block-1648576618227\"><div class=\"agni-block-separator-css\"><\/div><\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618230\"><\/div>\n\n\n\n<div class=\"agni-block-columns are-vertically-aligned-center has-columns-container agni-block-1648576618332\"><div class=\"agni-block-columns__contents\">\n<div class=\"agni-block-column agni-block-1648576618316\"><div class=\"agni-block-column__contents\">\n<div class=\"agni-block-spacer agni-block-1648576618233\"><\/div>\n\n\n\n<div class=\"agni-block-heading agni-block-1648576618239\"><h2>Our Standards<\/h2><\/div>\n\n\n\n<div class=\"agni-block-heading agni-block-1648576618245\"><h6>Torquent per conubia accumsan nulla in nostra<\/h6><\/div>\n\n\n\n<div class=\"agni-block-paragraph agni-block-1648576618250\"><p>Nullam accumsan nulla in arcu condimentum imperdiet. Class aptent taciti sociosqu ad litora torquent per conubia nostra, per inceptos himenaeos. Curabitur lacinia purus vitae lorem porttitor fermentum. In in mattis erat, eu mattis libero.<\/p><\/div>\n\n\n\n<div class=\"agni-block-paragraph agni-block-1648576618256\"><p>ociosqu ad litora torquent per conubia nostra, per inceptos himenaeos. Curabitur lacinia purus vitae lorem porttitor fermentum. In in mattis erat, eu mattis libero. Donec volutpat faucibus elit cursus interdum.<\/p><\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618260\"><\/div>\n\n\n\n<div class=\"agni-block-icon-cards agni-block-1648576618305\">\n<div class=\"agni-block-icon-card vertical has-icon-on-start agni-block-1648576618282\"><div class=\"agni-block-icon-card-icon\"><span class=\"agni-block-icon-card-icon__container\"><span class=\"agni-block-icon-svg__file\"><svg class=\"feather feather-target\" stroke-linejoin=\"round\" stroke-linecap=\"round\" stroke-width=\"1\" stroke=\"currentColor\" fill=\"none\" viewBox=\"0 0 24 24\" height=\"28\" width=\"28\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><circle r=\"10\" cy=\"12\" cx=\"12\"><\/circle><circle r=\"6\" cy=\"12\" cx=\"12\"><\/circle><circle r=\"2\" cy=\"12\" cx=\"12\"><\/circle><\/svg><\/span><\/span><\/div><div class=\"agni-block-icon-card__content\">\n<div class=\"agni-block-heading agni-block-1648576618266\"><h6 class=\"has-text-align-left\">Accurate Information<\/h6><\/div>\n\n\n\n<div class=\"agni-block-paragraph has-text-align-left agni-block-1648576618273\"><p>Cras volutpat, eros id tincidunt mollis, nibh lacus convallis ante felis.<\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"agni-block-icon-card vertical has-icon-on-start agni-block-1648576618300\"><div class=\"agni-block-icon-card-icon\"><span class=\"agni-block-icon-card-icon__container\"><span class=\"agni-block-icon-svg__file\"><svg class=\"feather feather-check-circle\" stroke-linejoin=\"round\" stroke-linecap=\"round\" stroke-width=\"1\" stroke=\"currentColor\" fill=\"none\" viewBox=\"0 0 24 24\" height=\"28\" width=\"28\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"><\/path><polyline points=\"22 4 12 14.01 9 11.01\"><\/polyline><\/svg><\/span><\/span><\/div><div class=\"agni-block-icon-card__content\">\n<div class=\"agni-block-heading agni-block-1648576618288\"><h6 class=\"has-text-align-left\">Possible Commitments<\/h6><\/div>\n\n\n\n<div class=\"agni-block-paragraph has-text-align-left agni-block-1648576618294\"><p>Cras volutpat, eros id tincidunt mollis, nibh lacus convallis ante felis.<\/p><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618308\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"agni-block-column agni-block-1648576618328\"><div class=\"agni-block-column__contents\">\n<figure class=\"agni-block-image size-full agni-block-1648576618320\"><img decoding=\"async\" src=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-12.png\" alt=\"\" class=\"wp-image-4757\"\/><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618335\"><\/div>\n\n\n\n<div class=\"agni-block-separator has-display-style-5 has-align-center has-columns-full agni-block-1648576618338\"><div class=\"agni-block-separator-css\"><\/div><\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618341\"><\/div>\n\n\n\n<div class=\"agni-block-columns has-columns-wide agni-block-1648576618420\"><div class=\"agni-block-columns__background\"><div class=\"agni-block-columns__background--color\"><\/div><\/div><div class=\"agni-block-columns__contents\">\n<div class=\"agni-block-column agni-block-1648576618362\"><div class=\"agni-block-column__contents\">\n<div class=\"agni-block-heading agni-block-1648576618348\"><h4>We Reached So Far<\/h4><\/div>\n\n\n\n<div class=\"agni-block-paragraph agni-block-1648576618354\"><p>Torquent per conubia accumsan nulla in nostra<\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"agni-block-column agni-block-1648576618415\"><div class=\"agni-block-column__contents\">\n<div class=\"agni-block-text-cards agni-block-1648576618408\">\n<div class=\"agni-block-text-card vertical has-text-on-center agni-block-1648576618372\"><h4 class=\"agni-block-text-card-text\">120+<\/h4><div class=\"agni-block-text-card__content\">\n<div class=\"agni-block-paragraph has-text-align-center agni-block-1648576618369\"><p>Stores around the world<\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"agni-block-text-card vertical has-text-on-center agni-block-1648576618383\"><h4 class=\"agni-block-text-card-text\">15M<\/h4><div class=\"agni-block-text-card__content\">\n<div class=\"agni-block-paragraph has-text-align-center agni-block-1648576618379\"><p>Products sold till date<\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"agni-block-text-card vertical has-text-on-center agni-block-1648576618393\"><h4 class=\"agni-block-text-card-text\">200K<\/h4><div class=\"agni-block-text-card__content\">\n<div class=\"agni-block-paragraph has-text-align-center agni-block-1648576618390\"><p>Registered users<\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"agni-block-text-card vertical has-text-on-center agni-block-1648576618402\"><h4 class=\"agni-block-text-card-text\">300+<\/h4><div class=\"agni-block-text-card__content\">\n<div class=\"agni-block-paragraph has-text-align-center agni-block-1648576618399\"><p>Brands available in store<\/p><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618424\"><\/div>\n\n\n\n<div class=\"agni-block-cards no-flex-grow agni-block-1648576618486\">\n<div class=\"agni-block-card vertical has-media-on-center agni-block-1648576618444\"><div class=\"agni-block-card__media\"><img decoding=\"async\" src=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-13.png\" alt=\"\" class=\"wp-image-4751\"\/><\/div><div class=\"agni-block-card__content\">\n<div class=\"agni-block-heading agni-block-1648576618430\"><h4 class=\"has-text-align-left\">Our Events & Happenings<\/h4><\/div>\n\n\n\n<div class=\"agni-block-paragraph has-text-align-left agni-block-1648576618437\"><p>Nullam accumsan nulla in arcu condimentum imperdiet. Class aptent taciti sociosqu ad litora<\/p><\/div>\n<\/div><a class=\"agni-block-card__link\" href=\"https:\/\/demo.agnidesigns.com\/cartify\/blog-grid\/\" target=\"_self\" rel=\"noopener\"><\/a><\/div>\n\n\n\n<div class=\"agni-block-card vertical has-media-on-center agni-block-1648576618463\"><div class=\"agni-block-card__media\"><img decoding=\"async\" src=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-14.png\" alt=\"\" class=\"wp-image-4752\"\/><\/div><div class=\"agni-block-card__content\">\n<div class=\"agni-block-heading agni-block-1648576618450\"><h4 class=\"has-text-align-left\">Work & Life Style<\/h4><\/div>\n\n\n\n<div class=\"agni-block-paragraph has-text-align-left agni-block-1648576618458\"><p>Nullam accumsan nulla in arcu condimentum imperdiet. Class aptent taciti sociosqu ad litora<\/p><\/div>\n<\/div><a class=\"agni-block-card__link\" href=\"https:\/\/demo.agnidesigns.com\/cartify\/portfolio\/\" target=\"_self\" rel=\"noopener\"><\/a><\/div>\n\n\n\n<div class=\"agni-block-card vertical has-media-on-center agni-block-1648576618481\"><div class=\"agni-block-card__media\"><img decoding=\"async\" src=\"https:\/\/demo.agnidesigns.com\/cartify\/wp-content\/uploads\/2021\/12\/about-image-15.png\" alt=\"\" class=\"wp-image-4753\"\/><\/div><div class=\"agni-block-card__content\">\n<div class=\"agni-block-heading agni-block-1648576618470\"><h4 class=\"has-text-align-left\">Career at Company<\/h4><\/div>\n\n\n\n<div class=\"agni-block-paragraph has-text-align-left agni-block-1648576618476\"><p>Nullam accumsan nulla in arcu condimentum imperdiet. Class aptent taciti sociosqu ad litora<\/p><\/div>\n<\/div><a class=\"agni-block-card__link\" href=\"https:\/\/demo.agnidesigns.com\/cartify\/contact-us-1\/\" target=\"_self\" rel=\"noopener\"><\/a><\/div>\n<\/div>\n\n\n\n<div class=\"agni-block-spacer agni-block-1648576618490\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"agni_page_title_hide":"on","agni_page_title_align":"","agni_page_margin_remove":"on","agni_page_bg_color":"","agni_page_bg_gradient":"","agni_page_header_source":"","agni_page_header_choice":null,"agni_footer_block_id":null,"agni_page_sidebar_choice":"","agni_slider_id":null,"agni_product_layout_choice":"","footnotes":""},"class_list":["post-4665","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/faetm.com\/index.php\/wp-json\/wp\/v2\/pages\/4665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faetm.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/faetm.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/faetm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/faetm.com\/index.php\/wp-json\/wp\/v2\/comments?post=4665"}],"version-history":[{"count":0,"href":"https:\/\/faetm.com\/index.php\/wp-json\/wp\/v2\/pages\/4665\/revisions"}],"wp:attachment":[{"href":"https:\/\/faetm.com\/index.php\/wp-json\/wp\/v2\/media?parent=4665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}